{"id":8,"count":1,"description":"","link":"\/blog\/tag\/vanlife\/","name":"VanLife","slug":"vanlife","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.vogtrv.com\/blog\/wp-json\/wp\/v2\/tags\/8"}],"collection":[{"href":"https:\/\/www.vogtrv.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.vogtrv.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.vogtrv.com\/blog\/wp-json\/wp\/v2\/posts?tags=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}